{"id":2524,"date":"2025-10-28T10:00:32","date_gmt":"2025-10-28T09:00:32","guid":{"rendered":"https:\/\/www.charlyverse.com\/?p=2524"},"modified":"2026-01-21T11:44:46","modified_gmt":"2026-01-21T10:44:46","slug":"recherche-en-ia-primee-a-bensheim","status":"publish","type":"post","link":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/","title":{"rendered":"Recherche en IA prim\u00e9e \u00e0 Bensheim"},"content":{"rendered":"<p>Nous sommes tr\u00e8s heureux de partager aujourd\u2019hui une histoire de r\u00e9ussite toute particuli\u00e8re de notre \u00e9quipe : notre coll\u00e8gue Ernesto Curmen a \u00e9t\u00e9 distingu\u00e9 pour son m\u00e9moire de master exceptionnel. Dans sa contribution, il nous donne lui-m\u00eame un aper\u00e7u du contenu passionnant et raconte quels th\u00e8mes l\u2019ont particuli\u00e8rement marqu\u00e9. Bonne lecture!<\/p>\n<p>Retrieval Augmented Generation, ou RAG en abr\u00e9g\u00e9, a chang\u00e9 pour toujours le paysage de la recherche documentaire. L\u2019approche de base est tr\u00e8s simple: les documents sont divis\u00e9s en sections de texte plus petites (<em>chunks<\/em>). Ces <em>chunks<\/em> sont ensuite convertis en <em>embeddings<\/em> (des repr\u00e9sentations vectorielles qui contiennent les informations s\u00e9mantiques du texte) et stock\u00e9s dans une base de donn\u00e9es. Apr\u00e8s ce processus, un utilisateur peut poser une question, dont l\u2019embedding est \u00e9galement cr\u00e9\u00e9 et plac\u00e9 dans la base, et ainsi tous les embeddings les plus proches sur le plan s\u00e9mantique peuvent \u00eatre retrouv\u00e9s. Ces passages de texte s\u00e9lectionn\u00e9s sont ensuite utilis\u00e9s pour g\u00e9n\u00e9rer la r\u00e9ponse finale.<\/p>\n<p>Il existe toutefois un probl\u00e8me central avec RAG : les solutions traditionnelles ignorent le contexte global, ce qui conduit souvent le syst\u00e8me \u00e0 ne pas trouver d\u2019informations pertinentes dans la base de connaissances. Par exemple, un utilisateur hypoth\u00e9tique pourrait poser la question suivante : \u00ab Quelles d\u00e9cisions ont \u00e9t\u00e9 prises concernant les prochaines \u00e9tapes \u00e0 l\u2019\u00e9cole Max Mustermann ? \u00bb Cet utilisateur souhaite obtenir des informations sur les d\u00e9lais, les \u00e9tapes \u00e0 venir et les accords pr\u00e9vus dans le cadre de la construction de l\u2019\u00e9cole. Pourtant, le chunk correspondant, qui contient la r\u00e9ponse, peut ne pas comporter de r\u00e9f\u00e9rence explicite \u00e0 l\u2019\u00e9cole Max Mustermann et ne peut donc pas \u00eatre correctement r\u00e9cup\u00e9r\u00e9 pour g\u00e9n\u00e9rer la r\u00e9ponse.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2510 aligncenter\" src=\"https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/10\/Picture1.png\" alt=\"L\u2019image montre un exemple graphique d\u2019une requ\u00eate RAG avec des segments mis en \u00e9vidence.\" width=\"589\" height=\"279\" srcset=\"https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/10\/Picture1.png 589w, https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/10\/Picture1-300x142.png 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/p>\n<p>Dans mon m\u00e9moire de master, j\u2019ai \u00e9tudi\u00e9 ce probl\u00e8me et mis en \u0153uvre l\u2019approche <strong>\u00ab <\/strong>Contextual-RAG<strong> \u00bb<\/strong> avec le corpus des protocoles parlementaires du groupe de recherche DisLab de l\u2019universit\u00e9 technique de Darmstadt. L\u2019\u00e9tape de contextualisation a lieu apr\u00e8s la division du texte en chunks et avant leur conversion en embeddings. Chaque chunk est enrichi d\u2019un contexte pertinent, issu d\u2019\u00e9nonc\u00e9s pr\u00e9c\u00e9dents ou suivants, ou m\u00eame li\u00e9 \u00e0 l\u2019id\u00e9e principale de l\u2019ensemble du texte. Chaque chunk est ainsi compl\u00e9t\u00e9 par des indices s\u00e9mantiques qui n\u2019\u00e9taient pas pr\u00e9sents auparavant mais qui peuvent d\u00e9sormais correspondre \u00e0 une requ\u00eate d\u2019utilisateur. Cette contextualisation a \u00e9t\u00e9 r\u00e9alis\u00e9e \u00e0 l\u2019aide de mod\u00e8les linguistiques locaux disponibles publiquement. Les r\u00e9sultats permettent de conclure que l\u2019application de Contextual-RAG \u00e0 la recherche dans un corpus politique atteint jusqu\u2019\u00e0 18 % de meilleures performances de rappel que l\u2019utilisation de Basic-RAG. Cela signifie que davantage de r\u00e9sultats pertinents sont trouv\u00e9s parmi les top-k r\u00e9ponses.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2514 aligncenter\" src=\"https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/10\/Picture2.png\" alt=\"L\u2019image montre un graphique \u00e0 barres pr\u00e9sentant les r\u00e9sultats de rappel et MRR de diff\u00e9rentes approches RAG.\" width=\"589\" height=\"257\" srcset=\"https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/10\/Picture2.png 589w, https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/10\/Picture2-300x131.png 300w\" sizes=\"auto, (max-width: 589px) 100vw, 589px\" \/><\/p>\n<p>Les connaissances et m\u00e9thodes acquises dans ce travail seront directement int\u00e9gr\u00e9es au logiciel d\u2019entreprise Inno:docs. Inno:docs est un chatbot bas\u00e9 sur l\u2019IA qui permet de rechercher des donn\u00e9es d\u2019entreprise en langage naturel et fournit des r\u00e9ponses factuelles. L\u2019approche Contextual-RAG permet au syst\u00e8me de trouver davantage de documents pertinents, puisque chaque chunk prend en compte le contexte complet du texte et n\u2019est pas stock\u00e9 isol\u00e9ment dans la base de donn\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Image : Innomatik AG<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous sommes tr\u00e8s heureux de partager aujourd\u2019hui une histoire de r\u00e9ussite toute particuli\u00e8re de notre \u00e9quipe : notre coll\u00e8gue Ernesto Curmen a \u00e9t\u00e9 distingu\u00e9 pour son m\u00e9moire de master exceptionnel. Dans sa contribution, il nous donne lui-m\u00eame un aper\u00e7u du contenu passionnant et raconte quels th\u00e8mes l\u2019ont particuli\u00e8rement marqu\u00e9. Bonne lecture! Retrieval Augmented Generation, ou [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":2518,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","osh_disable_topbar_sticky":"default","osh_disable_header_sticky":"default","osh_sticky_header_style":"default","osh_sticky_header_effect":"","osh_custom_sticky_logo":0,"osh_custom_retina_sticky_logo":0,"osh_custom_sticky_logo_height":0,"osh_background_color":"","osh_links_color":"","osh_links_hover_color":"","osh_links_active_color":"","osh_links_bg_color":"","osh_links_hover_bg_color":"","osh_links_active_bg_color":"","osh_menu_social_links_color":"","osh_menu_social_hover_links_color":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[111],"tags":[236,246,178,429,437,436],"class_list":["post-2524","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ia-robotique","tag-forschung-fr","tag-ia","tag-ki-fr","tag-logiciel","tag-rag","tag-recherche","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recherche en IA prim\u00e9e \u00e0 Bensheim | Charlyverse<\/title>\n<meta name=\"description\" content=\"Un projet d\u2019IA \u00e0 Bensheim a obtenu une distinction prestigieuse, marquant un important succ\u00e8s en recherche technologique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recherche en IA prim\u00e9e \u00e0 Bensheim | Charlyverse\" \/>\n<meta property=\"og:description\" content=\"Un projet d\u2019IA \u00e0 Bensheim a obtenu une distinction prestigieuse, marquant un important succ\u00e8s en recherche technologique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/\" \/>\n<meta property=\"og:site_name\" content=\"Charlyverse\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-28T09:00:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T10:44:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/10\/Charlyverse_Bild_Masterarbeit_Ernesto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jagoda Chomicka\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jagoda Chomicka\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/recherche-en-ia-primee-a-bensheim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/recherche-en-ia-primee-a-bensheim\\\/\"},\"author\":{\"name\":\"Jagoda Chomicka\",\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/#\\\/schema\\\/person\\\/997ac6772d9a4897117501456560d37e\"},\"headline\":\"Recherche en IA prim\u00e9e \u00e0 Bensheim\",\"datePublished\":\"2025-10-28T09:00:32+00:00\",\"dateModified\":\"2026-01-21T10:44:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/recherche-en-ia-primee-a-bensheim\\\/\"},\"wordCount\":580,\"publisher\":{\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/recherche-en-ia-primee-a-bensheim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charlyverse.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Charlyverse_Bild_Masterarbeit_Ernesto.jpg\",\"keywords\":[\"Forschung\",\"IA\",\"KI\",\"logiciel\",\"RAG\",\"recherche\"],\"articleSection\":[\"IA &amp; robotique\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/recherche-en-ia-primee-a-bensheim\\\/\",\"url\":\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/recherche-en-ia-primee-a-bensheim\\\/\",\"name\":\"Recherche en IA prim\u00e9e \u00e0 Bensheim | Charlyverse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/recherche-en-ia-primee-a-bensheim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/recherche-en-ia-primee-a-bensheim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.charlyverse.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Charlyverse_Bild_Masterarbeit_Ernesto.jpg\",\"datePublished\":\"2025-10-28T09:00:32+00:00\",\"dateModified\":\"2026-01-21T10:44:46+00:00\",\"description\":\"Un projet d\u2019IA \u00e0 Bensheim a obtenu une distinction prestigieuse, marquant un important succ\u00e8s en recherche technologique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/recherche-en-ia-primee-a-bensheim\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/recherche-en-ia-primee-a-bensheim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/recherche-en-ia-primee-a-bensheim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.charlyverse.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Charlyverse_Bild_Masterarbeit_Ernesto.jpg\",\"contentUrl\":\"https:\\\/\\\/www.charlyverse.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Charlyverse_Bild_Masterarbeit_Ernesto.jpg\",\"width\":1200,\"height\":800,\"caption\":\"L\u2019image montre Ernesto tenant son dipl\u00f4me de master devant l\u2019entr\u00e9e de l\u2019entreprise.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/recherche-en-ia-primee-a-bensheim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.charlyverse.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recherche en IA prim\u00e9e \u00e0 Bensheim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/#website\",\"url\":\"https:\\\/\\\/www.charlyverse.com\\\/\",\"name\":\"Charlyverse\",\"description\":\"Home\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.charlyverse.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/#organization\",\"name\":\"Charlyverse\",\"url\":\"https:\\\/\\\/www.charlyverse.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.charlyverse.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Charlyverse_Favicon_32x32.png\",\"contentUrl\":\"https:\\\/\\\/www.charlyverse.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Charlyverse_Favicon_32x32.png\",\"width\":32,\"height\":32,\"caption\":\"Charlyverse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.charlyverse.com\\\/#\\\/schema\\\/person\\\/997ac6772d9a4897117501456560d37e\",\"name\":\"Jagoda Chomicka\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ad99bc605c1317b7da216e33fcbcd1740187a536e6a4e50e8fe39cf5fde88db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ad99bc605c1317b7da216e33fcbcd1740187a536e6a4e50e8fe39cf5fde88db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3ad99bc605c1317b7da216e33fcbcd1740187a536e6a4e50e8fe39cf5fde88db?s=96&d=mm&r=g\",\"caption\":\"Jagoda Chomicka\"},\"url\":\"https:\\\/\\\/www.charlyverse.com\\\/fr\\\/author\\\/jagodachomicka\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recherche en IA prim\u00e9e \u00e0 Bensheim | Charlyverse","description":"Un projet d\u2019IA \u00e0 Bensheim a obtenu une distinction prestigieuse, marquant un important succ\u00e8s en recherche technologique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/","og_locale":"fr_FR","og_type":"article","og_title":"Recherche en IA prim\u00e9e \u00e0 Bensheim | Charlyverse","og_description":"Un projet d\u2019IA \u00e0 Bensheim a obtenu une distinction prestigieuse, marquant un important succ\u00e8s en recherche technologique.","og_url":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/","og_site_name":"Charlyverse","article_published_time":"2025-10-28T09:00:32+00:00","article_modified_time":"2026-01-21T10:44:46+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/10\/Charlyverse_Bild_Masterarbeit_Ernesto.jpg","type":"image\/jpeg"}],"author":"Jagoda Chomicka","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Jagoda Chomicka","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/#article","isPartOf":{"@id":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/"},"author":{"name":"Jagoda Chomicka","@id":"https:\/\/www.charlyverse.com\/#\/schema\/person\/997ac6772d9a4897117501456560d37e"},"headline":"Recherche en IA prim\u00e9e \u00e0 Bensheim","datePublished":"2025-10-28T09:00:32+00:00","dateModified":"2026-01-21T10:44:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/"},"wordCount":580,"publisher":{"@id":"https:\/\/www.charlyverse.com\/#organization"},"image":{"@id":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/10\/Charlyverse_Bild_Masterarbeit_Ernesto.jpg","keywords":["Forschung","IA","KI","logiciel","RAG","recherche"],"articleSection":["IA &amp; robotique"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/","url":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/","name":"Recherche en IA prim\u00e9e \u00e0 Bensheim | Charlyverse","isPartOf":{"@id":"https:\/\/www.charlyverse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/#primaryimage"},"image":{"@id":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/#primaryimage"},"thumbnailUrl":"https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/10\/Charlyverse_Bild_Masterarbeit_Ernesto.jpg","datePublished":"2025-10-28T09:00:32+00:00","dateModified":"2026-01-21T10:44:46+00:00","description":"Un projet d\u2019IA \u00e0 Bensheim a obtenu une distinction prestigieuse, marquant un important succ\u00e8s en recherche technologique.","breadcrumb":{"@id":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/#primaryimage","url":"https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/10\/Charlyverse_Bild_Masterarbeit_Ernesto.jpg","contentUrl":"https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/10\/Charlyverse_Bild_Masterarbeit_Ernesto.jpg","width":1200,"height":800,"caption":"L\u2019image montre Ernesto tenant son dipl\u00f4me de master devant l\u2019entr\u00e9e de l\u2019entreprise."},{"@type":"BreadcrumbList","@id":"https:\/\/www.charlyverse.com\/fr\/recherche-en-ia-primee-a-bensheim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/www.charlyverse.com\/"},{"@type":"ListItem","position":2,"name":"Recherche en IA prim\u00e9e \u00e0 Bensheim"}]},{"@type":"WebSite","@id":"https:\/\/www.charlyverse.com\/#website","url":"https:\/\/www.charlyverse.com\/","name":"Charlyverse","description":"Home","publisher":{"@id":"https:\/\/www.charlyverse.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.charlyverse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.charlyverse.com\/#organization","name":"Charlyverse","url":"https:\/\/www.charlyverse.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.charlyverse.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/05\/Charlyverse_Favicon_32x32.png","contentUrl":"https:\/\/www.charlyverse.com\/wp-content\/uploads\/2025\/05\/Charlyverse_Favicon_32x32.png","width":32,"height":32,"caption":"Charlyverse"},"image":{"@id":"https:\/\/www.charlyverse.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.charlyverse.com\/#\/schema\/person\/997ac6772d9a4897117501456560d37e","name":"Jagoda Chomicka","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3ad99bc605c1317b7da216e33fcbcd1740187a536e6a4e50e8fe39cf5fde88db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3ad99bc605c1317b7da216e33fcbcd1740187a536e6a4e50e8fe39cf5fde88db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3ad99bc605c1317b7da216e33fcbcd1740187a536e6a4e50e8fe39cf5fde88db?s=96&d=mm&r=g","caption":"Jagoda Chomicka"},"url":"https:\/\/www.charlyverse.com\/fr\/author\/jagodachomicka\/"}]}},"_links":{"self":[{"href":"https:\/\/www.charlyverse.com\/fr\/wp-json\/wp\/v2\/posts\/2524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.charlyverse.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.charlyverse.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.charlyverse.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.charlyverse.com\/fr\/wp-json\/wp\/v2\/comments?post=2524"}],"version-history":[{"count":1,"href":"https:\/\/www.charlyverse.com\/fr\/wp-json\/wp\/v2\/posts\/2524\/revisions"}],"predecessor-version":[{"id":2525,"href":"https:\/\/www.charlyverse.com\/fr\/wp-json\/wp\/v2\/posts\/2524\/revisions\/2525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.charlyverse.com\/fr\/wp-json\/wp\/v2\/media\/2518"}],"wp:attachment":[{"href":"https:\/\/www.charlyverse.com\/fr\/wp-json\/wp\/v2\/media?parent=2524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.charlyverse.com\/fr\/wp-json\/wp\/v2\/categories?post=2524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.charlyverse.com\/fr\/wp-json\/wp\/v2\/tags?post=2524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}